{"id":6698,"date":"2026-05-02T20:32:25","date_gmt":"2026-05-02T18:32:25","guid":{"rendered":"https:\/\/subaruperformance.com.py\/fueltech\/product\/cableado-wb-o2-nano-4-2-4-9\/"},"modified":"2026-05-02T20:32:25","modified_gmt":"2026-05-02T18:32:25","slug":"cableado-wb-o2-nano-4-2-4-9","status":"publish","type":"product","link":"https:\/\/subaruperformance.com.py\/fueltech\/product\/cableado-wb-o2-nano-4-2-4-9\/","title":{"rendered":"CABLEADO WB O2-NANO 4.2 \/ 4.9"},"content":{"rendered":"<p>Cableado para conectar sensores de banda ancha 4.2 o 4.9. La diferencia radica en el tama\u00f1o de las fichas del conector.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cableado para conectar sensores de banda ancha 4.2 o 4.9. La diferencia radica en el tama\u00f1o de las fichas del conector.<\/p>\n","protected":false},"featured_media":6697,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[18],"product_tag":[],"class_list":{"0":"post-6698","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-uncategorized","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/product\/6698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/comments?post=6698"}],"version-history":[{"count":0,"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/product\/6698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/media\/6697"}],"wp:attachment":[{"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/media?parent=6698"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/product_brand?post=6698"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/product_cat?post=6698"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/subaruperformance.com.py\/fueltech\/wp-json\/wp\/v2\/product_tag?post=6698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}